{"id":9387,"date":"2021-04-06T00:22:12","date_gmt":"2021-04-06T00:22:12","guid":{"rendered":"http:\/\/www.unica.edu.pe\/noticias\/?p=9387"},"modified":"2021-04-06T00:22:12","modified_gmt":"2021-04-06T00:22:12","slug":"avances-en-la-obra-de-reconstruccion-y-equipamiento-de-la-facultad-de-ingenieria-pesquera-y-alimentos-2","status":"publish","type":"post","link":"https:\/\/www.unica.edu.pe\/noticias\/2021\/04\/06\/avances-en-la-obra-de-reconstruccion-y-equipamiento-de-la-facultad-de-ingenieria-pesquera-y-alimentos-2\/","title":{"rendered":"Avances en la  obra de reconstrucci\u00f3n y equipamiento de la facultad de Ingenier\u00eda Pesquera y Alimentos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/hashtag\/plandeemergencia?__eep__=6&amp;__cft__[0]=AZUinypVQ5ADFWyt6AZP8Qp7xvrUojEI7RbuP37cyWeVmprxMlbc57GeUmvRoW-invEn1ELIQIi7EmytdLiZhdxbNO1e14q-06uaXRzLX1uCEDiHynudBnX4otNFWUidrMzAAKLOYyLNJajMA4SvFW1EyaeXQMkJQrj90Mj0kA7kWxUEvBDfT_DhX-kvhCMPkpI&amp;__tn__=*NK-R\">#PlanDeEmergencia<\/a> | En Pisco, contin\u00faa avanzando la obra de reconstrucci\u00f3n y equipamiento de la facultad de Ingenier\u00eda Pesquera y Alimentos. El mi\u00e9rcoles 31 de marzo, se realiz\u00f3 el llenado de techo en el \u00e1rea destinada a las actividades administrativas. En este pabell\u00f3n administrativo, se realiz\u00f3 el desmontado de todo el fierro existente que se encontraba en mal estado, y se trabaj\u00f3 en el nuevo encofrado, este pabell\u00f3n contar\u00e1 con dos pisos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"772\" height=\"436\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2021\/04\/gfdgd.jpg\" alt=\"\" class=\"wp-image-9388\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2021\/04\/gfdgd.jpg 772w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2021\/04\/gfdgd-300x169.jpg 300w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2021\/04\/gfdgd-768x434.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&#038;href=https%3A%2F%2Fwww.facebook.com%2FUnicaSLG%2Fvideos%2F297517705225284%2F&#038;show_text=false&#038;width=560\" width=\"560\" height=\"314\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\" allowFullScreen=\"true\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>#PlanDeEmergencia | En Pisco, contin\u00faa avanzando la obra de reconstrucci\u00f3n y equipamiento de la facultad de Ingenier\u00eda Pesquera y Alimentos. El mi\u00e9rcoles 31 de marzo, se realiz\u00f3 el llenado de techo en el \u00e1rea destinada a las actividades administrativas. En este pabell\u00f3n administrativo, se realiz\u00f3 el desmontado de todo el fierro existente que se encontraba &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.unica.edu.pe\/noticias\/2021\/04\/06\/avances-en-la-obra-de-reconstruccion-y-equipamiento-de-la-facultad-de-ingenieria-pesquera-y-alimentos-2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abAvances en la  obra de reconstrucci\u00f3n y equipamiento de la facultad de Ingenier\u00eda Pesquera y Alimentos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9387","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/9387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/comments?post=9387"}],"version-history":[{"count":1,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/9387\/revisions"}],"predecessor-version":[{"id":9389,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/9387\/revisions\/9389"}],"wp:attachment":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/media?parent=9387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/categories?post=9387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/tags?post=9387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}