{"id":33699,"date":"2025-02-06T15:27:00","date_gmt":"2025-02-06T20:27:00","guid":{"rendered":"https:\/\/www.unica.edu.pe\/noticias\/?p=33699"},"modified":"2025-02-11T17:08:30","modified_gmt":"2025-02-11T22:08:30","slug":"la-oficima-de-tecnologias-de-la-informacion-viene-realizando-la-implantacion-de-las-pantallas-informativas-en-las-diversas-facultades","status":"publish","type":"post","link":"https:\/\/www.unica.edu.pe\/noticias\/2025\/02\/06\/la-oficima-de-tecnologias-de-la-informacion-viene-realizando-la-implantacion-de-las-pantallas-informativas-en-las-diversas-facultades\/","title":{"rendered":"LA OFICINA DE TECNOLOG\u00cdAS DE LA INFORMACI\u00d3N, VIENE REALIZANDO LA IMPLANTACI\u00d3N DE LAS PANTALLAS INFORMATIVAS EN LAS DIVERSAS FACULTADES."},"content":{"rendered":"\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/pantallasinteractivas?__eep__=6&amp;__cft__[0]=AZUNAKILTKOjHomCEaIq9PxGeFtoqG-7Fabh1aS-RHq4regH4321z2T0S5HSHplzv7YkeYzdiLGE-AgHD_bTxtkJw1m6GumSw9SEo-LMTqjfQm0LyYsFG6pjH6AFEktXQcj7m246oBjT4g2Vs5BchLOFjOjyV3UFTi09cNz08-f3h3WqC6NHFSFs2YdeGAM72OA&amp;__tn__=*NK-R\">#Pantallasinteractivas<\/a> | La Oficina de Tecnolog\u00edas de la Informaci\u00f3n, OTI, viene realizando la implantaci\u00f3n de las pantallas interactivas en las diversas facultades; es as\u00ed que ya se ha realizado en las facultades de Ciencias Biol\u00f3gicas, Odontolog\u00eda y Agronom\u00eda.<\/p>\n\n\n\n<p>Este trabajo se viene realizando de acuerdo a lo dispuesto por nuestro rector, el Dr. Dante Calder\u00f3n Huaman\u00ed. Recordemos que el pasado 15 de enero fue presentada esta herramienta tecnol\u00f3gica; desde esa fecha se ha <a><\/a>venido haciendo la entrega a las diversas facultades y ahora ya nos encontramos en su implementaci\u00f3n.<\/p>\n\n\n\n<p>Estas herramientas modernas permitir\u00e1n a nuestros estudiantes y docentes interactuar de manera m\u00e1s din\u00e1mica y creativa durante el desarrollo de sus clases.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"684\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2025\/02\/image-64.png\" alt=\"\" class=\"wp-image-33700\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2025\/02\/image-64.png 683w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2025\/02\/image-64-300x300.png 300w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2025\/02\/image-64-150x150.png 150w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2025\/02\/image-64-100x100.png 100w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>#Pantallasinteractivas | La Oficina de Tecnolog\u00edas de la Informaci\u00f3n, OTI, viene realizando la implantaci\u00f3n de las pantallas interactivas en las diversas facultades; es as\u00ed que ya se ha realizado en las facultades de Ciencias Biol\u00f3gicas, Odontolog\u00eda y Agronom\u00eda. Este trabajo se viene realizando de acuerdo a lo dispuesto por nuestro rector, el Dr. Dante Calder\u00f3n &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.unica.edu.pe\/noticias\/2025\/02\/06\/la-oficima-de-tecnologias-de-la-informacion-viene-realizando-la-implantacion-de-las-pantallas-informativas-en-las-diversas-facultades\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLA OFICINA DE TECNOLOG\u00cdAS DE LA INFORMACI\u00d3N, VIENE REALIZANDO LA IMPLANTACI\u00d3N DE LAS PANTALLAS INFORMATIVAS EN LAS DIVERSAS FACULTADES.\u00bb<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-33699","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/33699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/comments?post=33699"}],"version-history":[{"count":2,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/33699\/revisions"}],"predecessor-version":[{"id":33702,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/33699\/revisions\/33702"}],"wp:attachment":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/media?parent=33699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/categories?post=33699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/tags?post=33699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}