{"id":33225,"date":"2025-01-17T15:39:00","date_gmt":"2025-01-17T20:39:00","guid":{"rendered":"https:\/\/www.unica.edu.pe\/noticias\/?p=33225"},"modified":"2025-01-20T08:41:20","modified_gmt":"2025-01-20T13:41:20","slug":"el-elenco-de-danzas-de-la-universidad-nacional-san-luis-gonzaga-realizo-su-presentacion-con-la-danza-de-los-negritos-en-el-parque-central-de-boqueron","status":"publish","type":"post","link":"https:\/\/www.unica.edu.pe\/noticias\/2025\/01\/17\/el-elenco-de-danzas-de-la-universidad-nacional-san-luis-gonzaga-realizo-su-presentacion-con-la-danza-de-los-negritos-en-el-parque-central-de-boqueron\/","title":{"rendered":"El Elenco de Danzas de la Universidad Nacional \u00abSan Luis Gonzaga\u00bb realizo su presentaci\u00f3n con la Danza de los Negritos en el Parque Central de Boquer\u00f3n."},"content":{"rendered":"\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/participacionartistica?__eep__=6&amp;__cft__[0]=AZW3xVee6EBHSrNAHwZzLnG2e47UCabTuXNNJ0TowW5Jl1VlVAo9UHiOigKpbKjmwphCWJVEbhj9X4p-SfnFAbn5Ta0WV4fzOEgNiAvwNBaKeGuzK7slLRvIV9uVFS0jZNzLp9ozoOn5pXIYjM34ENytJ3juucDi-7LqB4oyPNIj3EJO9S6bxN5LHQsBSo1561to1L_Rd4dNELbMWo2UajQH&amp;__tn__=*NK-R\">#Participacionartistica<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/festivalinternacional2025?__eep__=6&amp;__cft__[0]=AZW3xVee6EBHSrNAHwZzLnG2e47UCabTuXNNJ0TowW5Jl1VlVAo9UHiOigKpbKjmwphCWJVEbhj9X4p-SfnFAbn5Ta0WV4fzOEgNiAvwNBaKeGuzK7slLRvIV9uVFS0jZNzLp9ozoOn5pXIYjM34ENytJ3juucDi-7LqB4oyPNIj3EJO9S6bxN5LHQsBSo1561to1L_Rd4dNELbMWo2UajQH&amp;__tn__=*NK-R\">#FestivalInternacional2025<\/a><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf89\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8c\/1\/16\/1f389.png\"><\/p>\n\n\n\n<p>El d\u00eda de ayer el Elenco de Danzas de la <a href=\"https:\/\/www.facebook.com\/UnicaSLG?__cft__[0]=AZW3xVee6EBHSrNAHwZzLnG2e47UCabTuXNNJ0TowW5Jl1VlVAo9UHiOigKpbKjmwphCWJVEbhj9X4p-SfnFAbn5Ta0WV4fzOEgNiAvwNBaKeGuzK7slLRvIV9uVFS0jZNzLp9ozoOn5pXIYjM34ENytJ3juucDi-7LqB4oyPNIj3EJO9S6bxN5LHQsBSo1561to1L_Rd4dNELbMWo2UajQH&amp;__tn__=-]K-R\">Universidad Nacional \u00abSan Luis Gonzaga\u00bb<\/a> realizo su presentaci\u00f3n con la Danza de los Negritos en el Parque Central de Boquer\u00f3n, considerado uno de los distritos m\u00e1s importantes de la Provincia de Chiriqui &#8211; Panam\u00e1.<img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udde6\ud83c\uddf9\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t4a\/1\/16\/1f1e6_1f1f9.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddf5\ud83c\udde6\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tc6\/1\/16\/1f1f5_1f1e6.png\"><\/p>\n\n\n\n<p>Estas actividades se vienen realizando como parte del 10mo Festival Internacional organizado por el Conjunto Folkl\u00f3rico \u00abRa\u00edces y Tradiciones\u00bb, quienes brindan todas <a><\/a>las atenciones a las delegaciones representantes de Per\u00fa, Bolivia, M\u00e9xico, Colombia, Costa Rica .<img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc83\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tc7\/1\/16\/1f483.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udd7a\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t97\/1\/16\/1f57a.png\"><\/p>\n\n\n\n<p>.<\/p>\n\n\n\n<p>.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/panama?__eep__=6&amp;__cft__[0]=AZW3xVee6EBHSrNAHwZzLnG2e47UCabTuXNNJ0TowW5Jl1VlVAo9UHiOigKpbKjmwphCWJVEbhj9X4p-SfnFAbn5Ta0WV4fzOEgNiAvwNBaKeGuzK7slLRvIV9uVFS0jZNzLp9ozoOn5pXIYjM34ENytJ3juucDi-7LqB4oyPNIj3EJO9S6bxN5LHQsBSo1561to1L_Rd4dNELbMWo2UajQH&amp;__tn__=*NK-R\">#Panama<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/festivalinternacional?__eep__=6&amp;__cft__[0]=AZW3xVee6EBHSrNAHwZzLnG2e47UCabTuXNNJ0TowW5Jl1VlVAo9UHiOigKpbKjmwphCWJVEbhj9X4p-SfnFAbn5Ta0WV4fzOEgNiAvwNBaKeGuzK7slLRvIV9uVFS0jZNzLp9ozoOn5pXIYjM34ENytJ3juucDi-7LqB4oyPNIj3EJO9S6bxN5LHQsBSo1561to1L_Rd4dNELbMWo2UajQH&amp;__tn__=*NK-R\">#FestivalInternacional<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/danzafolclorica?__eep__=6&amp;__cft__[0]=AZW3xVee6EBHSrNAHwZzLnG2e47UCabTuXNNJ0TowW5Jl1VlVAo9UHiOigKpbKjmwphCWJVEbhj9X4p-SfnFAbn5Ta0WV4fzOEgNiAvwNBaKeGuzK7slLRvIV9uVFS0jZNzLp9ozoOn5pXIYjM34ENytJ3juucDi-7LqB4oyPNIj3EJO9S6bxN5LHQsBSo1561to1L_Rd4dNELbMWo2UajQH&amp;__tn__=*NK-R\">#DanzaFolclorica<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/elperuenlosojosdelmundo?__eep__=6&amp;__cft__[0]=AZW3xVee6EBHSrNAHwZzLnG2e47UCabTuXNNJ0TowW5Jl1VlVAo9UHiOigKpbKjmwphCWJVEbhj9X4p-SfnFAbn5Ta0WV4fzOEgNiAvwNBaKeGuzK7slLRvIV9uVFS0jZNzLp9ozoOn5pXIYjM34ENytJ3juucDi-7LqB4oyPNIj3EJO9S6bxN5LHQsBSo1561to1L_Rd4dNELbMWo2UajQH&amp;__tn__=*NK-R\">#ElPeruenlosojosdelmundo<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/UnicaSLG\/posts\/pfbid02YrMCbZ5e8wVzKDMEf2kMRhzaEyFVpmrz3ufF62De2UAX6ddw1TRfNFEYiDLbaAHcl\">https:\/\/www.facebook.com\/UnicaSLG\/posts\/pfbid02YrMCbZ5e8wVzKDMEf2kMRhzaEyFVpmrz3ufF62De2UAX6ddw1TRfNFEYiDLbaAHcl<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"683\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2025\/01\/image-121.png\" alt=\"\" class=\"wp-image-33226\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2025\/01\/image-121.png 681w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2025\/01\/image-121-300x300.png 300w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2025\/01\/image-121-150x150.png 150w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2025\/01\/image-121-100x100.png 100w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>#Participacionartistica #FestivalInternacional2025 El d\u00eda de ayer el Elenco de Danzas de la Universidad Nacional \u00abSan Luis Gonzaga\u00bb realizo su presentaci\u00f3n con la Danza de los Negritos en el Parque Central de Boquer\u00f3n, considerado uno de los distritos m\u00e1s importantes de la Provincia de Chiriqui &#8211; Panam\u00e1. Estas actividades se vienen realizando como parte del 10mo &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.unica.edu.pe\/noticias\/2025\/01\/17\/el-elenco-de-danzas-de-la-universidad-nacional-san-luis-gonzaga-realizo-su-presentacion-con-la-danza-de-los-negritos-en-el-parque-central-de-boqueron\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl Elenco de Danzas de la Universidad Nacional \u00abSan Luis Gonzaga\u00bb realizo su presentaci\u00f3n con la Danza de los Negritos en el Parque Central de Boquer\u00f3n.\u00bb<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-33225","post","type-post","status-publish","format-standard","hentry","category-proyeccion-social"],"_links":{"self":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/33225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/comments?post=33225"}],"version-history":[{"count":1,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/33225\/revisions"}],"predecessor-version":[{"id":33227,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/33225\/revisions\/33227"}],"wp:attachment":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/media?parent=33225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/categories?post=33225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/tags?post=33225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}