{"id":28867,"date":"2024-05-02T08:10:00","date_gmt":"2024-05-02T13:10:00","guid":{"rendered":"https:\/\/www.unica.edu.pe\/noticias\/?p=28867"},"modified":"2024-05-21T15:17:11","modified_gmt":"2024-05-21T20:17:11","slug":"medio-de-comunicacion-nacional-latina-informa-la-creacion-de-un-repelente-contra-la-picadura-del-zancudo","status":"publish","type":"post","link":"https:\/\/www.unica.edu.pe\/noticias\/2024\/05\/02\/medio-de-comunicacion-nacional-latina-informa-la-creacion-de-un-repelente-contra-la-picadura-del-zancudo\/","title":{"rendered":"Medio de comunicaci\u00f3n Nacional #Latina informa la creaci\u00f3n de un repelente contra la picadura del zancudo"},"content":{"rendered":"\n<p>#Repelente I Medio de comunicaci\u00f3n Nacional #Latina informa la creaci\u00f3n de un repelente contra la picadura del zancudo que transmite el dengue por estudiantes y docentes de la facultad de Farmacia y Bioqu\u00edmica.<\/p>\n\n\n\n<p>Ver nota:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/UnicaSLG\/posts\/pfbid0o5J6V7p2hNN63urf4FkowzfBNsZSTCBsnGNWym5KxZqY6ifxSqMkWt5LRAXPb8hpl\">https:\/\/www.facebook.com\/UnicaSLG\/posts\/pfbid0o5J6V7p2hNN63urf4FkowzfBNsZSTCBsnGNWym5KxZqY6ifxSqMkWt5LRAXPb8hpl<\/a> <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"506\" height=\"418\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2024\/05\/145.png\" alt=\"\" class=\"wp-image-28868\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2024\/05\/145.png 506w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2024\/05\/145-300x248.png 300w\" sizes=\"auto, (max-width: 506px) 100vw, 506px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>#Repelente I Medio de comunicaci\u00f3n Nacional #Latina informa la creaci\u00f3n de un repelente contra la picadura del zancudo que transmite el dengue por estudiantes y docentes de la facultad de Farmacia y Bioqu\u00edmica. Ver nota: https:\/\/www.facebook.com\/UnicaSLG\/posts\/pfbid0o5J6V7p2hNN63urf4FkowzfBNsZSTCBsnGNWym5KxZqY6ifxSqMkWt5LRAXPb8hpl<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-28867","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/28867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/comments?post=28867"}],"version-history":[{"count":1,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/28867\/revisions"}],"predecessor-version":[{"id":28869,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/28867\/revisions\/28869"}],"wp:attachment":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/media?parent=28867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/categories?post=28867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/tags?post=28867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}