{"id":25922,"date":"2023-09-26T15:00:00","date_gmt":"2023-09-26T20:00:00","guid":{"rendered":"https:\/\/www.unica.edu.pe\/noticias\/?p=25922"},"modified":"2023-10-23T12:47:39","modified_gmt":"2023-10-23T17:47:39","slug":"ceremonia-central-por-los-38o-aniversario-de-funcionamiento-de-la-facultad-de-ciencias","status":"publish","type":"post","link":"https:\/\/www.unica.edu.pe\/noticias\/2023\/09\/26\/ceremonia-central-por-los-38o-aniversario-de-funcionamiento-de-la-facultad-de-ciencias\/","title":{"rendered":"Ceremonia central por los 38\u00ba aniversario de funcionamiento de la facultad de Ciencias"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/facultadciencias?__eep__=6&amp;__cft__[0]=AZWvQPhqMinu__g9UEgVImvD7aP90aWC01KihCt53ZoaJ_QCIDT6VLgH-tyA6TyD5lTyHJAVCSRSiHPVpi4hfSmj8smhb873P4eTOe3xA_RsyqngueS9AbLpMm0Uz-E0mjcfzyad9PFpDOaRlojgsG6zhGyMPpto0rs7LXtGteZPx_Ej22Z1loz9QN07yFO8hJI&amp;__tn__=*NK-R\">#FacultadCiencias<\/a> | El fin de semana se realiz\u00f3 ceremonia central por los 38\u00ba aniversario de funcionamiento de la facultad de Ciencias, la ceremonia se llev\u00f3 acab\u00f3 en el teatro Abraham Valdelomar y conto con la presencia del Dr. Rub\u00e9n Tito Flores decano de la facultad.<\/p>\n\n\n\n<p>Al decano lo acompa\u00f1aron la Dra. Lludy Missa Franco, presidenta de la comisi\u00f3n de aniversario, Dr. Carlos Aparcana Aquije, Dr. Jaime Quintana Beramendi y el Dr. M\u00e1ximo Huamani Licas integrantes de la comisi\u00f3n de <a><\/a>aniversario.<\/p>\n\n\n\n<p>En la ceremonia se realiz\u00f3 la premiaci\u00f3n a los ganadores de la Primera Olimpiada de Matem\u00e1ticas denominada \u00abJos\u00e9 Contreras Choquez\u00bb:<\/p>\n\n\n\n<p>Resultados Individuales:<\/p>\n\n\n\n<p>Categor\u00eda A:<\/p>\n\n\n\n<p>5to a\u00f1o<\/p>\n\n\n\n<p>1ro Razabal Ramos, Dessyret Juleysi de la I.E Daniel Merino Ruiz.<\/p>\n\n\n\n<p>2do Bonifaz Chacaliaza, Juan Daniel de la I.E San Luis Gonzaga<\/p>\n\n\n\n<p>4to a\u00f1o<\/p>\n\n\n\n<p>1ro. Pinco Apaza, Carlos Eduardo de la I.E Daniel Merino Ruiz.<\/p>\n\n\n\n<p>2do. Nieto Villa, Andrea Carolina de la I.E Antonia Moreno de C\u00e1ceres<\/p>\n\n\n\n<p>Categor\u00eda B:<\/p>\n\n\n\n<p>5to a\u00f1o<\/p>\n\n\n\n<p>1ro Ram\u00edrez Uribe, Guillermo Farid de la I.E.P Saco Oliveros<\/p>\n\n\n\n<p>2do Balbuena Lara, Andr\u00e9 Francisco de la I.E.P Jos\u00e9 Carlos Mari\u00e1tegui<\/p>\n\n\n\n<p>4to a\u00f1o<\/p>\n\n\n\n<p>1ro Vidalon Ventura, Braulio Estefano de la I.E.P Sant\u00edsimo Jes\u00fas<\/p>\n\n\n\n<p>2do Yupanqui Mallma, Rodrigo Fernando de la I.E.P Geniomatic Rodas<\/p>\n\n\n\n<p>Resultados generales:<\/p>\n\n\n\n<p>Categor\u00eda A:<\/p>\n\n\n\n<p>1ro. I.E Daniel Merino Ruiz.<\/p>\n\n\n\n<p>2do I.E San Luis Gonzaga<\/p>\n\n\n\n<p>Categor\u00eda B:<\/p>\n\n\n\n<p>1ro I.E.P Saco Oliveros<\/p>\n\n\n\n<p>2do I.E.P Geniomatic Rodas<\/p>\n\n\n\n<p>Al final de la ceremonia central se presentaron los nueros art\u00edsticos, la tuna universitaria y los danzantes de tijeras, culminado con un almuerzo de confraternidad<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/32-1-1024x683.jpg\" alt=\"\" class=\"wp-image-25924\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/32-1-1024x683.jpg 1024w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/32-1-300x200.jpg 300w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/32-1-768x512.jpg 768w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/32-1-1536x1024.jpg 1536w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/32-1.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/29-1-1024x683.jpg\" alt=\"\" class=\"wp-image-25925\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/29-1-1024x683.jpg 1024w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/29-1-300x200.jpg 300w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/29-1-768x512.jpg 768w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/29-1-1536x1024.jpg 1536w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/29-1.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/30-1024x683.jpg\" alt=\"\" class=\"wp-image-25926\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/30-1024x683.jpg 1024w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/30-300x200.jpg 300w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/30-768x512.jpg 768w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/30-1536x1024.jpg 1536w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/30.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/31-1024x683.jpg\" alt=\"\" class=\"wp-image-25927\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/31-1024x683.jpg 1024w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/31-300x200.jpg 300w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/31-768x512.jpg 768w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/31-1536x1024.jpg 1536w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2023\/10\/31.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>#FacultadCiencias | El fin de semana se realiz\u00f3 ceremonia central por los 38\u00ba aniversario de funcionamiento de la facultad de Ciencias, la ceremonia se llev\u00f3 acab\u00f3 en el teatro Abraham Valdelomar y conto con la presencia del Dr. Rub\u00e9n Tito Flores decano de la facultad. Al decano lo acompa\u00f1aron la Dra. Lludy Missa Franco, presidenta &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.unica.edu.pe\/noticias\/2023\/09\/26\/ceremonia-central-por-los-38o-aniversario-de-funcionamiento-de-la-facultad-de-ciencias\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCeremonia central por los 38\u00ba aniversario de funcionamiento de la facultad de Ciencias\u00bb<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-25922","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/25922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/comments?post=25922"}],"version-history":[{"count":1,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/25922\/revisions"}],"predecessor-version":[{"id":25928,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/25922\/revisions\/25928"}],"wp:attachment":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/media?parent=25922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/categories?post=25922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/tags?post=25922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}