{"id":17176,"date":"2022-09-05T08:54:35","date_gmt":"2022-09-05T13:54:35","guid":{"rendered":"https:\/\/www.unica.edu.pe\/noticias\/?p=17176"},"modified":"2022-09-05T08:54:36","modified_gmt":"2022-09-05T13:54:36","slug":"bolsa-de-trabajo-encargado-de-abastecimiento","status":"publish","type":"post","link":"https:\/\/www.unica.edu.pe\/noticias\/2022\/09\/05\/bolsa-de-trabajo-encargado-de-abastecimiento\/","title":{"rendered":"Bolsa De Trabajo: Encargado de abastecimiento"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/bolsadetrabajo?__eep__=6&amp;__cft__[0]=AZUZp8KROppisdsDd2fAhgjEIaS-D0SnDrTs9FAFkoPdZN6s8O_DN_whhbDT_G_V8x8UM-ote3HVRbFdXLJH3WObfi7i4xM0zdm1VtKHBoQvHlVw_YwZWjZ5XyAoNndvxUXTa0_Y7iPPfefnOFuiD9OrZG-NUpOlLrB7OXvBW-ovWw&amp;__tn__=*NK-R\">#BolsaDeTrabajo<\/a> | Encargado de abastecimiento.<\/p>\n\n\n\n<p>Enlace para el ingreso a la plataforma: <a href=\"https:\/\/bolsadetrabajo.unica.edu.pe\/?fbclid=IwAR0Kt6sKtQ3nFy26cau4FLvNouVQBm3aRMqn8AkHVu5Bp9f0iCnSzTzZVGc\" rel=\"noreferrer noopener\" target=\"_blank\">https:\/\/bolsadetrabajo.unica.edu.pe\/<\/a><\/p>\n\n\n\n<p>Usuario: C\u00f3digo de matr\u00edcula.<\/p>\n\n\n\n<p>Contrase\u00f1a: N\u00famero de DNI.<\/p>\n\n\n\n<p>Vigencia: 14 de setiembre.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"887\" height=\"686\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/09\/image-13.png\" alt=\"\" class=\"wp-image-17177\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/09\/image-13.png 887w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/09\/image-13-300x232.png 300w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/09\/image-13-768x594.png 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>#BolsaDeTrabajo | Encargado de abastecimiento. Enlace para el ingreso a la plataforma: https:\/\/bolsadetrabajo.unica.edu.pe\/ Usuario: C\u00f3digo de matr\u00edcula. Contrase\u00f1a: N\u00famero de DNI. Vigencia: 14 de setiembre.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17176","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/17176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/comments?post=17176"}],"version-history":[{"count":1,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/17176\/revisions"}],"predecessor-version":[{"id":17178,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/17176\/revisions\/17178"}],"wp:attachment":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/media?parent=17176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/categories?post=17176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/tags?post=17176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}