{"id":15671,"date":"2022-06-30T09:20:00","date_gmt":"2022-06-30T14:20:00","guid":{"rendered":"https:\/\/www.unica.edu.pe\/noticias\/?p=15671"},"modified":"2022-06-30T12:58:04","modified_gmt":"2022-06-30T17:58:04","slug":"campana-de-medida-de-presion-arterial-entrevista-emocional-con-los-psicologos-del-servicio-psicopedagogico","status":"publish","type":"post","link":"https:\/\/www.unica.edu.pe\/noticias\/2022\/06\/30\/campana-de-medida-de-presion-arterial-entrevista-emocional-con-los-psicologos-del-servicio-psicopedagogico\/","title":{"rendered":"Campa\u00f1a de medida de presi\u00f3n arterial, entrevista emocional con los psic\u00f3logos del servicio psicopedag\u00f3gico"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/bienestaruniversitario?__eep__=6&amp;__cft__[0]=AZXc0vDwKhjSH-2mcaeHpy7WXD_lx7EMZJUdnbTYBhzb4sGLh3GjSnAb4emAqkFAQlW6OupTsXBOCDXA_0WjAT_NN-5_QqugNVvg-1lnzEOhf33iIZnWKhD8USvEtVNiIfG5cjc--WCw4A4RsdgP8bc6RwNGOJsM1xsfV64ZeyA5M_E_3qDTGkjJcEeBAYygbfQKKNDo4wwx4OiLvIK6oaek&amp;__tn__=*NK-R\">#BienestarUniversitario<\/a> | La direcci\u00f3n de Bienestar Universitario de la UNICA, viene realizando campa\u00f1as en beneficio de los estudiantes y trabajadores de nuestra universidad. El martes realizaron la actividad consistente en la medida de presi\u00f3n arterial, entrevista emocional con los psic\u00f3logos del servicio psicopedag\u00f3gico, charlas referidas al correcto uso de las mascarillas, en la facultad de Ciencias de la Educaci\u00f3n y Humanidades.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172-1024x768.jpg\" alt=\"\" class=\"wp-image-15672\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172-1024x768.jpg 1024w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172-300x225.jpg 300w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172-768x576.jpg 768w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172-1536x1152.jpg 1536w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172.jpg 1600w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/173-768x1024.jpg\" alt=\"\" class=\"wp-image-15673\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/173-768x1024.jpg 768w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/173-225x300.jpg 225w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/173-1152x1536.jpg 1152w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/173.jpg 1200w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/174-768x1024.jpg\" alt=\"\" class=\"wp-image-15674\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/174-768x1024.jpg 768w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/174-225x300.jpg 225w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/174-1152x1536.jpg 1152w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/174.jpg 1200w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/175-1024x768.jpg\" alt=\"\" class=\"wp-image-15675\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/175-1024x768.jpg 1024w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/175-300x225.jpg 300w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/175-768x576.jpg 768w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/175-1536x1152.jpg 1536w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/175.jpg 1600w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172-1-1024x768.jpg\" alt=\"\" class=\"wp-image-15676\" srcset=\"https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172-1-1024x768.jpg 1024w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172-1-300x225.jpg 300w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172-1-768x576.jpg 768w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172-1-1536x1152.jpg 1536w, https:\/\/www.unica.edu.pe\/noticias\/wp-content\/uploads\/2022\/06\/172-1.jpg 1600w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>#BienestarUniversitario | La direcci\u00f3n de Bienestar Universitario de la UNICA, viene realizando campa\u00f1as en beneficio de los estudiantes y trabajadores de nuestra universidad. El martes realizaron la actividad consistente en la medida de presi\u00f3n arterial, entrevista emocional con los psic\u00f3logos del servicio psicopedag\u00f3gico, charlas referidas al correcto uso de las mascarillas, en la facultad de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.unica.edu.pe\/noticias\/2022\/06\/30\/campana-de-medida-de-presion-arterial-entrevista-emocional-con-los-psicologos-del-servicio-psicopedagogico\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCampa\u00f1a de medida de presi\u00f3n arterial, entrevista emocional con los psic\u00f3logos del servicio psicopedag\u00f3gico\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-15671","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/15671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/comments?post=15671"}],"version-history":[{"count":1,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/15671\/revisions"}],"predecessor-version":[{"id":15677,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/posts\/15671\/revisions\/15677"}],"wp:attachment":[{"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/media?parent=15671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/categories?post=15671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unica.edu.pe\/noticias\/wp-json\/wp\/v2\/tags?post=15671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}